{"id":13574,"date":"2026-03-12T15:55:37","date_gmt":"2026-03-12T22:55:37","guid":{"rendered":"https:\/\/elmontgomery.com\/?p=13574"},"modified":"2026-03-12T15:55:37","modified_gmt":"2026-03-12T22:55:37","slug":"status-of-arizona-surface-water-supplies-march-2026","status":"publish","type":"post","link":"https:\/\/elmontgomery.com\/es\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/","title":{"rendered":"Estado de los suministros de agua superficial en Arizona: marzo de 2026"},"content":{"rendered":"<p>La siguiente tabla resume el estado de los principales suministros de agua superficial de Arizona para el mes de marzo. \n<table id=\"tablepress-50\" class=\"tablepress tablepress-id-50\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">2026<\/th><th class=\"column-3\">2025<\/th><th class=\"column-4\">2024<\/th><th class=\"column-5\">2023<\/th><th class=\"column-6\">2022<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>SISTEMA DEL R\u00cdO COLORADO<\/strong><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Lago Powell (% completo)<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">34<\/td><td class=\"column-4\">34<\/td><td class=\"column-5\">23<\/td><td class=\"column-6\">25<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Lago Mead (% lleno)<\/td><td class=\"column-2\">34<\/td><td class=\"column-3\">35<\/td><td class=\"column-4\">37<\/td><td class=\"column-5\">28<\/td><td class=\"column-6\">34<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Sistema Colorado total (% completo)<\/td><td class=\"column-2\">37<\/td><td class=\"column-3\">41<\/td><td class=\"column-4\">42<\/td><td class=\"column-5\">32<\/td><td class=\"column-6\">36<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Elevaci\u00f3n del lago Mead (ft msl)<\/td><td class=\"column-2\">1,066<\/td><td class=\"column-3\">1,068<\/td><td class=\"column-4\">1,076<\/td><td class=\"column-5\">1,046<\/td><td class=\"column-6\">1,066<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Elevaci\u00f3n de declaraci\u00f3n de escasez de nivel 1 (ft msl)<\/td><td class=\"column-2\">1,075<\/td><td class=\"column-3\">1,075<\/td><td class=\"column-4\">1,075<\/td><td class=\"column-5\">1,075<\/td><td class=\"column-6\">1,075<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Elevaci\u00f3n de declaraci\u00f3n de escasez de nivel 2a (ft msl)<\/td><td class=\"column-2\">1,050<\/td><td class=\"column-3\">1,050<\/td><td class=\"column-4\">1,050<\/td><td class=\"column-5\">1,050<\/td><td class=\"column-6\">1,050<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Elevaci\u00f3n de declaraci\u00f3n de escasez de nivel 2b (ft msl)<\/td><td class=\"column-2\">1,045<\/td><td class=\"column-3\">1,045<\/td><td class=\"column-4\">1,045<\/td><td class=\"column-5\">1,045<\/td><td class=\"column-6\">1,045<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Elevaci\u00f3n de declaraci\u00f3n de escasez de nivel 3 (ft msl)<\/td><td class=\"column-2\">1,025<\/td><td class=\"column-3\">1,025<\/td><td class=\"column-4\">1,025<\/td><td class=\"column-5\">1,025<\/td><td class=\"column-6\">1,025<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Elevaci\u00f3n del lago Powell (ft msl)<\/td><td class=\"column-2\">3,530<\/td><td class=\"column-3\">3,562<\/td><td class=\"column-4\">3,561<\/td><td class=\"column-5\">3,520<\/td><td class=\"column-6\">3,526<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Elevaci\u00f3n m\u00ednima de generaci\u00f3n de energ\u00eda (ft msl)<\/td><td class=\"column-2\">3,490<\/td><td class=\"column-3\">3,490<\/td><td class=\"column-4\">3,490<\/td><td class=\"column-5\">3,490<\/td><td class=\"column-6\">3,490<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Agua de la cuenca superior Precipitaci\u00f3n anual hasta la fecha (% de promedio)<\/td><td class=\"column-2\">90<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">101<\/td><td class=\"column-5\">125<\/td><td class=\"column-6\">100<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Capa de nieve actual de la cuenca superior (% de promedio)<\/td><td class=\"column-2\">68<\/td><td class=\"column-3\">91<\/td><td class=\"column-4\">104<\/td><td class=\"column-5\">139<\/td><td class=\"column-6\">92<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\"><strong>SISTEMA SAL \/ R\u00cdO VERDE<\/strong><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Embalses de Salt River (% full)<\/td><td class=\"column-2\">56<\/td><td class=\"column-3\">73<\/td><td class=\"column-4\">89<\/td><td class=\"column-5\">90<\/td><td class=\"column-6\">77<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Embalses R\u00edo Verde (% full)<\/td><td class=\"column-2\">67<\/td><td class=\"column-3\">52<\/td><td class=\"column-4\">55<\/td><td class=\"column-5\">82<\/td><td class=\"column-6\">37<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Sistema Total Salt \/ Verde (% full)<\/td><td class=\"column-2\">57<\/td><td class=\"column-3\">70<\/td><td class=\"column-4\">85<\/td><td class=\"column-5\">89<\/td><td class=\"column-6\">72<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Precipitaci\u00f3n anual de agua salada\/verde hasta la fecha (% de promedio)<\/td><td class=\"column-2\">95<\/td><td class=\"column-3\">77<\/td><td class=\"column-4\">77<\/td><td class=\"column-5\">146<\/td><td class=\"column-6\">73<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Nivel actual de capa de nieve Salt\/Verde (% de promedio)<\/td><td class=\"column-2\">6<\/td><td class=\"column-3\">88<\/td><td class=\"column-4\">88<\/td><td class=\"column-5\">278<\/td><td class=\"column-6\">92<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\"><strong>ALMACENAMIENTO DE TAPAS<\/strong><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Lago Agradable (% completo)<\/td><td class=\"column-2\">54<\/td><td class=\"column-3\">61<\/td><td class=\"column-4\">73<\/td><td class=\"column-5\">66<\/td><td class=\"column-6\">85<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-50 from cache --><\/p>","protected":false},"excerpt":{"rendered":"<p>The following table summarizes the status of Arizona\u2019s key surface  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-13574","post","type-post","status-publish","format-standard","hentry","category-az-surface-water-status"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Status of Arizona surface water supplies: March 2026 - Montgomery &amp; Associates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elmontgomery.com\/es\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Status of Arizona surface water supplies: March 2026 - Montgomery &amp; Associates\" \/>\n<meta property=\"og:description\" content=\"The following table summarizes the status of Arizona\u2019s key surface [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elmontgomery.com\/es\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Montgomery &amp; Associates\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T22:55:37+00:00\" \/>\n<meta name=\"author\" content=\"Bonnie Gradillas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bonnie Gradillas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/\"},\"author\":{\"name\":\"Bonnie Gradillas\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#\\\/schema\\\/person\\\/58759a5fff045f0abed4a7dd73f21a80\"},\"headline\":\"Status of Arizona surface water supplies: March 2026\",\"datePublished\":\"2026-03-12T22:55:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/\"},\"wordCount\":27,\"publisher\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#organization\"},\"articleSection\":[\"AZ Surface Water Status\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/\",\"url\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/\",\"name\":\"Status of Arizona surface water supplies: March 2026 - Montgomery &amp; Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#website\"},\"datePublished\":\"2026-03-12T22:55:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/az-surface-water-status\\\/status-of-arizona-surface-water-supplies-march-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elmontgomery.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AZ Surface Water Status\",\"item\":\"https:\\\/\\\/elmontgomery.com\\\/category\\\/az-surface-water-status\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Status of Arizona surface water supplies: March 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#website\",\"url\":\"https:\\\/\\\/elmontgomery.com\\\/\",\"name\":\"Montgomery &amp; Associates\",\"description\":\"Water Resource Consultants\",\"publisher\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elmontgomery.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#organization\",\"name\":\"Montgomery &amp; Associates\",\"url\":\"https:\\\/\\\/elmontgomery.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elmontgomery.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/MA_RGB_hrz_tag-1.png\",\"contentUrl\":\"https:\\\/\\\/elmontgomery.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/MA_RGB_hrz_tag-1.png\",\"width\":1833,\"height\":533,\"caption\":\"Montgomery &amp; Associates\"},\"image\":{\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2434577\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/#\\\/schema\\\/person\\\/58759a5fff045f0abed4a7dd73f21a80\",\"name\":\"Bonnie Gradillas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/elmontgomery.com\\\/wp-content\\\/litespeed\\\/avatar\\\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966\",\"url\":\"https:\\\/\\\/elmontgomery.com\\\/wp-content\\\/litespeed\\\/avatar\\\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966\",\"contentUrl\":\"https:\\\/\\\/elmontgomery.com\\\/wp-content\\\/litespeed\\\/avatar\\\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966\",\"caption\":\"Bonnie Gradillas\"},\"url\":\"https:\\\/\\\/elmontgomery.com\\\/es\\\/author\\\/bonnie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estado de los recursos h\u00eddricos superficiales de Arizona: marzo de 2026 - Montgomery &amp; Associates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elmontgomery.com\/es\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Status of Arizona surface water supplies: March 2026 - Montgomery &amp; Associates","og_description":"The following table summarizes the status of Arizona\u2019s key surface [...]","og_url":"https:\/\/elmontgomery.com\/es\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/","og_site_name":"Montgomery &amp; Associates","article_published_time":"2026-03-12T22:55:37+00:00","author":"Bonnie Gradillas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bonnie Gradillas"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/#article","isPartOf":{"@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/"},"author":{"name":"Bonnie Gradillas","@id":"https:\/\/elmontgomery.com\/#\/schema\/person\/58759a5fff045f0abed4a7dd73f21a80"},"headline":"Status of Arizona surface water supplies: March 2026","datePublished":"2026-03-12T22:55:37+00:00","mainEntityOfPage":{"@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/"},"wordCount":27,"publisher":{"@id":"https:\/\/elmontgomery.com\/#organization"},"articleSection":["AZ Surface Water Status"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/","url":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/","name":"Estado de los recursos h\u00eddricos superficiales de Arizona: marzo de 2026 - Montgomery &amp; Associates","isPartOf":{"@id":"https:\/\/elmontgomery.com\/#website"},"datePublished":"2026-03-12T22:55:37+00:00","breadcrumb":{"@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elmontgomery.com\/az-surface-water-status\/status-of-arizona-surface-water-supplies-march-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elmontgomery.com\/"},{"@type":"ListItem","position":2,"name":"AZ Surface Water Status","item":"https:\/\/elmontgomery.com\/category\/az-surface-water-status\/"},{"@type":"ListItem","position":3,"name":"Status of Arizona surface water supplies: March 2026"}]},{"@type":"WebSite","@id":"https:\/\/elmontgomery.com\/#website","url":"https:\/\/elmontgomery.com\/","name":"Montgomery y asociados","description":"Consultores de recursos h\u00eddricos","publisher":{"@id":"https:\/\/elmontgomery.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elmontgomery.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/elmontgomery.com\/#organization","name":"Montgomery y asociados","url":"https:\/\/elmontgomery.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/elmontgomery.com\/#\/schema\/logo\/image\/","url":"https:\/\/elmontgomery.com\/wp-content\/uploads\/2022\/09\/MA_RGB_hrz_tag-1.png","contentUrl":"https:\/\/elmontgomery.com\/wp-content\/uploads\/2022\/09\/MA_RGB_hrz_tag-1.png","width":1833,"height":533,"caption":"Montgomery &amp; Associates"},"image":{"@id":"https:\/\/elmontgomery.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/2434577\/"]},{"@type":"Person","@id":"https:\/\/elmontgomery.com\/#\/schema\/person\/58759a5fff045f0abed4a7dd73f21a80","name":"Bonnie Gradillas","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/elmontgomery.com\/wp-content\/litespeed\/avatar\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966","url":"https:\/\/elmontgomery.com\/wp-content\/litespeed\/avatar\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966","contentUrl":"https:\/\/elmontgomery.com\/wp-content\/litespeed\/avatar\/162a33d9412f88762a55a5ac8405b1b3.jpg?ver=1778545966","caption":"Bonnie Gradillas"},"url":"https:\/\/elmontgomery.com\/es\/author\/bonnie\/"}]}},"_links":{"self":[{"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/posts\/13574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/comments?post=13574"}],"version-history":[{"count":1,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/posts\/13574\/revisions"}],"predecessor-version":[{"id":13575,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/posts\/13574\/revisions\/13575"}],"wp:attachment":[{"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/media?parent=13574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/categories?post=13574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elmontgomery.com\/es\/wp-json\/wp\/v2\/tags?post=13574"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}